{"id":1636,"date":"2021-07-02T10:20:00","date_gmt":"2021-07-02T13:20:00","guid":{"rendered":"http:\/\/gestaoderestaurantes.com.br\/blog\/index.php\/2011\/08\/16\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/"},"modified":"2021-10-01T11:00:15","modified_gmt":"2021-10-01T14:00:15","slug":"limpeza-de-coifas-evitam-acidentes-em-restaurantes","status":"publish","type":"post","link":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/","title":{"rendered":"Limpeza de Coifas evitam acidentes em restaurantes"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><a href=\"http:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2011\/08\/image3.png\"><img decoding=\"async\" src=\"http:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2011\/08\/image_thumb1.png\" alt=\"image\"\/><\/a><\/figure>\n\n\n\n<p>&nbsp;<strong>As coifas e os dutos de exaust\u00e3o em cozinhas industriais devem receber uma limpeza peri\u00f3dica a fim de se evitar o ac\u00famulo de gordura em seu interior.<\/strong><\/p>\n\n\n\n<p>O ac\u00famulo de gordura pode causar v\u00e1rios transtornos que v\u00e3o desde a contamina\u00e7\u00e3o de alimentos a explos\u00f5es. Coifas com excesso de gordura podem gotejar a gordura de volta para a \u00e1rea de coc\u00e7\u00e3o contaminando alimentos. Outro risco oferecido pela m\u00e1 manuten\u00e7\u00e3o das coifas \u00e9 o ac\u00famulo de gordura e gases em seu interior podendo causar explos\u00f5es e inc\u00eandios.<\/p>\n\n\n\n<p>\u00c9 necess\u00e1rio que a coifa e seus dutos recebam limpezas peri\u00f3dicas aplicando-se produtos removedores de gordura. Ap\u00f3s a aplica\u00e7\u00e3o dos removedores deve-se fazer a raspagem interna eliminando todo o excesso de gordura. Em casos mais extremos h\u00e1 a necessidade da desmontagem de algumas partes do duto para uma limpeza mas eficiente.<\/p>\n\n\n\n<p>\u00c9 recomendado que a limpeza das coifas e dutos sejam feitas a cada 3 meses. \u00c9 importante tamb\u00e9m a utiliza\u00e7\u00e3o de equipamentos de prote\u00e7\u00e3o individual para as pessoas encarregadas pela limpeza como luvas, \u00f3culos e m\u00e1scaras de prote\u00e7\u00e3o. Como os produtos utilizados para tal tarefa s\u00e3o extremamente fortes e intoxicantes tais equipamentos s\u00e3o indispens\u00e1veis para se evitar a queima das m\u00e3os, contato com os olhos e a inala\u00e7\u00e3o dos gases produzidos durante a limpeza.<\/p>\n\n\n\n<p>H\u00e1 no mercado empresas especializadas na limpeza destes equipamentos. A vantagem na contrata\u00e7\u00e3o destas empresas est\u00e1 na seguran\u00e7a, efici\u00eancia e agilidade,<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"font-size: small;\">Fonte: <\/span><a href=\"http:\/\/www.gestaoderestaurantes.com.br\"><span style=\"font-size: small;\">www.gestaoderestaurantes.com.br<\/span><\/a><\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"http:\/\/www.gestaoderestaurantes.com.br\/loja_virtual.html\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"170\" src=\"http:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2008\/02\/banners_cozinha_industrial.png\" alt=\"banners_cozinha_industrial\" class=\"wp-image-5400\" srcset=\"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2008\/02\/banners_cozinha_industrial.png 500w, https:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2008\/02\/banners_cozinha_industrial-300x102.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/figure><\/div>\n\n\n\n<!-- Formul\u00e1rio -->\n<div style=\"background-color:#730447; padding:15px\">\n<div style=\"font-size:30px; color:#ffffff;\">Quer manter-se atualizado? Cadastre-se!!!<\/div>\n<!-- Formul\u00e1rio -->\n<style>body  <\/style>\n   <link rel=\"stylesheet\" href=\"https:\/\/blob.llimages.com\/machine-files\/all-css\/form-ll.css\">\n   <form action=\"https:\/\/paginas.rocks\/Pages\/Index\/282943\" method=\"post\" target=\"_blank\">  \n   <input id=\"id\" name=\"id\" type=\"hidden\" value=\"282943\">  \n   <input id=\"pid\" name=\"pid\" type=\"hidden\" value=\"10613273\">  \n   <input id=\"list_id\" name=\"list_id\" type=\"hidden\" value=\"282943\">  \n   <input id=\"provider\" name=\"provider\" type=\"hidden\" value=\"leadlovers\">   \n   <label for=\"name\">Nome:<\/label>   \n   <input class=\"form-control form-ll\" id=\"name\" name=\"name\" placeholder=\"Informe o seu nome\" type=\"text\">   \n   <label for=\"email\">E-mail:<\/label>   \n   <input class=\"form-control form-ll\" id=\"email\" name=\"email\" placeholder=\"Informe o seu email\" type=\"text\">  \n   <button class=\"btn btn-danger\" style=\"padding: 10px 40px; margin:15px 0 5px; background-color: rgba(230, 130, 0, 1); border-color: rgba(230, 130, 0, 1) !important; \" type=\"submit\">CADASTRAR<\/button>  \n   <input type=\"hidden\" id=\"source\" name=\"source\" value=\"\">  \n   <img decoding=\"async\" src=\"https:\/\/llimages.com\/redirect\/redirect.aspx?A=V&amp;p=10613273&amp;m=282943\" style=\"display: none;\">\n<\/form>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;As coifas e os dutos de exaust\u00e3o em cozinhas industriais devem receber uma limpeza peri\u00f3dica a fim de se evitar o ac\u00famulo de gordura em seu interior. O ac\u00famulo de gordura pode causar v\u00e1rios transtornos que v\u00e3o desde a contamina\u00e7\u00e3o de alimentos a explos\u00f5es. Coifas com excesso de gordura podem gotejar a gordura de volta [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,57,17,20],"tags":[151,339,341,340,338],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Limpeza de Coifas evitam acidentes em restaurantes - GEST\u00c3O DE RESTAURANTES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Limpeza de Coifas evitam acidentes em restaurantes - GEST\u00c3O DE RESTAURANTES\" \/>\n<meta property=\"og:description\" content=\"&nbsp;As coifas e os dutos de exaust\u00e3o em cozinhas industriais devem receber uma limpeza peri\u00f3dica a fim de se evitar o ac\u00famulo de gordura em seu interior. O ac\u00famulo de gordura pode causar v\u00e1rios transtornos que v\u00e3o desde a contamina\u00e7\u00e3o de alimentos a explos\u00f5es. Coifas com excesso de gordura podem gotejar a gordura de volta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/\" \/>\n<meta property=\"og:site_name\" content=\"GEST\u00c3O DE RESTAURANTES\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-02T13:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-01T14:00:15+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2011\/08\/image_thumb1.png\" \/>\n<meta name=\"author\" content=\"Gest\u00e3o de Restaurantes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gest\u00e3o de Restaurantes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/\"},\"author\":{\"name\":\"Gest\u00e3o de Restaurantes\",\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/#\/schema\/person\/f81faea281d148e85942baf46f9cbbd5\"},\"headline\":\"Limpeza de Coifas evitam acidentes em restaurantes\",\"datePublished\":\"2021-07-02T13:20:00+00:00\",\"dateModified\":\"2021-10-01T14:00:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/\"},\"wordCount\":269,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2011\/08\/image_thumb1.png\",\"keywords\":[\"coifa\",\"coifas\",\"desencrustantes\",\"dutos\",\"limpeza\"],\"articleSection\":[\"Dicas\",\"Equipamentos\",\"Higiene e Limpeza\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/\",\"url\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/\",\"name\":\"Limpeza de Coifas evitam acidentes em restaurantes - GEST\u00c3O DE RESTAURANTES\",\"isPartOf\":{\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2011\/08\/image_thumb1.png\",\"datePublished\":\"2021-07-02T13:20:00+00:00\",\"dateModified\":\"2021-10-01T14:00:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#primaryimage\",\"url\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2011\/08\/image_thumb1.png\",\"contentUrl\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2011\/08\/image_thumb1.png\",\"width\":\"240\",\"height\":\"180\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Limpeza de Coifas evitam acidentes em restaurantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/#website\",\"url\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/\",\"name\":\"GEST\u00c3O DE RESTAURANTES\",\"description\":\"Cursos para Restaurantes e Bares\",\"publisher\":{\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/#organization\",\"name\":\"GEST\u00c3O DE RESTAURANTES\",\"url\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2017\/02\/logo.png\",\"contentUrl\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2017\/02\/logo.png\",\"width\":150,\"height\":150,\"caption\":\"GEST\u00c3O DE RESTAURANTES\"},\"image\":{\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/#\/schema\/person\/f81faea281d148e85942baf46f9cbbd5\",\"name\":\"Gest\u00e3o de Restaurantes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b589d30c197e3c258b1b65aa142c72b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b589d30c197e3c258b1b65aa142c72b5?s=96&d=mm&r=g\",\"caption\":\"Gest\u00e3o de Restaurantes\"},\"url\":\"https:\/\/gestaoderestaurantes.com.br\/blog\/author\/alisonalves\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Limpeza de Coifas evitam acidentes em restaurantes - GEST\u00c3O DE RESTAURANTES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/","og_locale":"pt_BR","og_type":"article","og_title":"Limpeza de Coifas evitam acidentes em restaurantes - GEST\u00c3O DE RESTAURANTES","og_description":"&nbsp;As coifas e os dutos de exaust\u00e3o em cozinhas industriais devem receber uma limpeza peri\u00f3dica a fim de se evitar o ac\u00famulo de gordura em seu interior. O ac\u00famulo de gordura pode causar v\u00e1rios transtornos que v\u00e3o desde a contamina\u00e7\u00e3o de alimentos a explos\u00f5es. Coifas com excesso de gordura podem gotejar a gordura de volta [&hellip;]","og_url":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/","og_site_name":"GEST\u00c3O DE RESTAURANTES","article_published_time":"2021-07-02T13:20:00+00:00","article_modified_time":"2021-10-01T14:00:15+00:00","og_image":[{"url":"http:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2011\/08\/image_thumb1.png","type":"","width":"","height":""}],"author":"Gest\u00e3o de Restaurantes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gest\u00e3o de Restaurantes","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#article","isPartOf":{"@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/"},"author":{"name":"Gest\u00e3o de Restaurantes","@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/#\/schema\/person\/f81faea281d148e85942baf46f9cbbd5"},"headline":"Limpeza de Coifas evitam acidentes em restaurantes","datePublished":"2021-07-02T13:20:00+00:00","dateModified":"2021-10-01T14:00:15+00:00","mainEntityOfPage":{"@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/"},"wordCount":269,"commentCount":7,"publisher":{"@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#primaryimage"},"thumbnailUrl":"http:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2011\/08\/image_thumb1.png","keywords":["coifa","coifas","desencrustantes","dutos","limpeza"],"articleSection":["Dicas","Equipamentos","Higiene e Limpeza","Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/","url":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/","name":"Limpeza de Coifas evitam acidentes em restaurantes - GEST\u00c3O DE RESTAURANTES","isPartOf":{"@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#primaryimage"},"image":{"@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#primaryimage"},"thumbnailUrl":"http:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2011\/08\/image_thumb1.png","datePublished":"2021-07-02T13:20:00+00:00","dateModified":"2021-10-01T14:00:15+00:00","breadcrumb":{"@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#primaryimage","url":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2011\/08\/image_thumb1.png","contentUrl":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2011\/08\/image_thumb1.png","width":"240","height":"180"},{"@type":"BreadcrumbList","@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/dicas\/limpeza-de-coifas-evitam-acidentes-em-restaurantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/gestaoderestaurantes.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Limpeza de Coifas evitam acidentes em restaurantes"}]},{"@type":"WebSite","@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/#website","url":"https:\/\/gestaoderestaurantes.com.br\/blog\/","name":"GEST\u00c3O DE RESTAURANTES","description":"Cursos para Restaurantes e Bares","publisher":{"@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gestaoderestaurantes.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/#organization","name":"GEST\u00c3O DE RESTAURANTES","url":"https:\/\/gestaoderestaurantes.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2017\/02\/logo.png","contentUrl":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-content\/uploads\/2017\/02\/logo.png","width":150,"height":150,"caption":"GEST\u00c3O DE RESTAURANTES"},"image":{"@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/#\/schema\/person\/f81faea281d148e85942baf46f9cbbd5","name":"Gest\u00e3o de Restaurantes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gestaoderestaurantes.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b589d30c197e3c258b1b65aa142c72b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b589d30c197e3c258b1b65aa142c72b5?s=96&d=mm&r=g","caption":"Gest\u00e3o de Restaurantes"},"url":"https:\/\/gestaoderestaurantes.com.br\/blog\/author\/alisonalves\/"}]}},"_links":{"self":[{"href":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-json\/wp\/v2\/posts\/1636"}],"collection":[{"href":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1636"}],"version-history":[{"count":4,"href":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-json\/wp\/v2\/posts\/1636\/revisions"}],"predecessor-version":[{"id":20309,"href":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-json\/wp\/v2\/posts\/1636\/revisions\/20309"}],"wp:attachment":[{"href":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gestaoderestaurantes.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}